{"id":16289,"date":"2026-03-24T17:11:34","date_gmt":"2026-03-24T20:11:34","guid":{"rendered":"https:\/\/agromedios.com\/new\/?p=16289"},"modified":"2026-03-24T17:12:44","modified_gmt":"2026-03-24T20:12:44","slug":"la-unidad-de-tecnologia-de-maccio-con-drones-y-capacitacion-en-el-centro-de-la-escena","status":"publish","type":"post","link":"https:\/\/agromedios.com\/new\/la-unidad-de-tecnologia-de-maccio-con-drones-y-capacitacion-en-el-centro-de-la-escena\/","title":{"rendered":"La Unidad de Tecnolog\u00eda de Macci\u00f3 con drones y capacitaci\u00f3n en el centro de la escena"},"content":{"rendered":"\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/agromedios.com\/new\/wp-content\/uploads\/2026\/03\/Andrea-Larosa.mp3\"><\/audio><\/figure>\n\n\n\n<p>Especial para www.agromedios.com,<\/p>\n\n\n\n<p>escribe Francisco Ferrer<\/p>\n\n\n\n<p>Durante la muestra, <strong>Andrea Larrosa<\/strong> y <strong>Santiago Soria<\/strong> compartieron la visi\u00f3n de la compa\u00f1\u00eda respecto a la integraci\u00f3n de estas herramientas en el esquema productivo actual. Seg\u00fan destacaron los referentes, la tecnolog\u00eda no es un fin en s\u00ed mismo, sino un medio para alcanzar la <strong>sostenibilidad econ\u00f3mica y ambiental<\/strong>.<\/p>\n\n\n\n<p>Uno de los puntos m\u00e1s altos de la participaci\u00f3n de la empresa fueron las <strong>actividades de capacitaci\u00f3n<\/strong> lideradas por <strong>Diego Oliva<\/strong>. Conscientes de que la curva de aprendizaje es el principal desaf\u00edo de la adopci\u00f3n tecnol\u00f3gica, las sesiones de formaci\u00f3n se centraron en:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Operativa Segura:<\/strong> Protocolos de vuelo y configuraci\u00f3n de equipos para aplicaciones de precisi\u00f3n.<\/li>\n\n\n\n<li><strong>Gesti\u00f3n de Datos:<\/strong> C\u00f3mo interpretar los mapas de reflectancia y salud vegetal para optimizar la fertilizaci\u00f3n y el control de plagas.<\/li>\n\n\n\n<li><strong>Mantenimiento Preventivo:<\/strong> Claves para asegurar la vida \u00fatil de las bater\u00edas y los sistemas de pulverizaci\u00f3n de los drones.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Especial para www.agromedios.com, escribe Francisco Ferrer Durante la muestra, Andrea Larrosa y Santiago Soria compartieron la visi\u00f3n de la compa\u00f1\u00eda respecto a la integraci\u00f3n de estas herramientas en el esquema productivo actual. Seg\u00fan destacaron los referentes, la tecnolog\u00eda no es un fin en s\u00ed mismo, sino un medio para alcanzar la sostenibilidad econ\u00f3mica y ambiental. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16290,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[3],"tags":[49],"class_list":["post-16289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","tag-e","entry","has-media"],"featured_image_urls":{"full":["https:\/\/agromedios.com\/new\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-4.57.27-PM.jpeg",1600,1200,false],"thumbnail":["https:\/\/agromedios.com\/new\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-4.57.27-PM-150x150.jpeg",150,150,true],"medium":["https:\/\/agromedios.com\/new\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-4.57.27-PM-300x225.jpeg",300,225,true],"medium_large":["https:\/\/agromedios.com\/new\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-4.57.27-PM-768x576.jpeg",768,576,true],"large":["https:\/\/agromedios.com\/new\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-4.57.27-PM-1024x768.jpeg",1024,768,true],"1536x1536":["https:\/\/agromedios.com\/new\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-4.57.27-PM-1536x1152.jpeg",1536,1152,true],"2048x2048":["https:\/\/agromedios.com\/new\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-4.57.27-PM.jpeg",1600,1200,false],"ocean-thumb-m":["https:\/\/agromedios.com\/new\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-4.57.27-PM-600x600.jpeg",600,600,true],"ocean-thumb-ml":["https:\/\/agromedios.com\/new\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-4.57.27-PM-800x450.jpeg",800,450,true],"ocean-thumb-l":["https:\/\/agromedios.com\/new\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-4.57.27-PM-1200x700.jpeg",1200,700,true]},"author_info":{"info":["Agromedios"]},"category_info":"<a href=\"https:\/\/agromedios.com\/new\/category\/eventos\/\" rel=\"category tag\">Eventos<\/a>","tag_info":"Eventos","comment_count":"0","_links":{"self":[{"href":"https:\/\/agromedios.com\/new\/wp-json\/wp\/v2\/posts\/16289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agromedios.com\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agromedios.com\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agromedios.com\/new\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agromedios.com\/new\/wp-json\/wp\/v2\/comments?post=16289"}],"version-history":[{"count":1,"href":"https:\/\/agromedios.com\/new\/wp-json\/wp\/v2\/posts\/16289\/revisions"}],"predecessor-version":[{"id":16292,"href":"https:\/\/agromedios.com\/new\/wp-json\/wp\/v2\/posts\/16289\/revisions\/16292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agromedios.com\/new\/wp-json\/wp\/v2\/media\/16290"}],"wp:attachment":[{"href":"https:\/\/agromedios.com\/new\/wp-json\/wp\/v2\/media?parent=16289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agromedios.com\/new\/wp-json\/wp\/v2\/categories?post=16289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agromedios.com\/new\/wp-json\/wp\/v2\/tags?post=16289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}